{"id":359,"date":"2020-03-13T18:01:44","date_gmt":"2020-03-13T18:01:44","guid":{"rendered":"http:\/\/saifandjasser.com\/?page_id=359"},"modified":"2023-11-27T11:41:10","modified_gmt":"2023-11-27T11:41:10","slug":"contact-us","status":"publish","type":"page","link":"https:\/\/sda.in.net\/web\/sajco\/contact-us\/","title":{"rendered":"Contact Us"},"content":{"rendered":"\r\n\t<section class=\"section\" id=\"section_368098053\">\n\t\t<div class=\"bg section-bg fill bg-fill  bg-loaded\" >\n\n\t\t\t\n\t\t\t\n\t\t\t\n\n\t\t<\/div>\n\n\t\t<div class=\"section-content relative\">\n\t\t\t\r\n\r\n\n  <div class=\"banner has-hover\" id=\"banner-1258897354\">\n          <div class=\"banner-inner fill\">\n        <div class=\"banner-bg fill\" >\n            <div class=\"bg fill bg-fill \"><\/div>\n                        <div class=\"overlay\"><\/div>            \n                    <\/div>\n        <div class=\"banner-layers container\">\n            <div class=\"fill banner-link\"><\/div>            \r\n\r\n   <div id=\"text-box-832116341\" class=\"text-box banner-layer x50 md-x50 lg-x50 y50 md-y50 lg-y50 res-text\">\n                                <div class=\"text dark\">\n              \n              <div class=\"text-inner text-center\">\n                  \r\n\r\n<h2><span style=\"color: #0054a4;\"><strong>Contact Us<\/strong><\/span><\/h2>\r\n\r\n              <\/div>\n           <\/div>\n                            \n<style>\n#text-box-832116341 {\n  width: 60%;\n}\n#text-box-832116341 .text {\n  font-size: 100%;\n}\n<\/style>\n    <\/div>\n \r\n\r\n        <\/div>\n      <\/div>\n\n            \n<style>\n#banner-1258897354 {\n  padding-top: 50%;\n}\n#banner-1258897354 .bg.bg-loaded {\n  background-image: url(https:\/\/sda.in.net\/web\/sajco\/wp-content\/uploads\/2020\/03\/Lifting-Equipment.jpg);\n}\n#banner-1258897354 .overlay {\n  background-color: rgba(0, 0, 0, 0);\n}\n#banner-1258897354 .bg {\n  background-position: 38% 70%;\n}\n<\/style>\n  <\/div>\n\n\r\n\r\n\t\t<\/div>\n\n\t\t\n<style>\n#section_368098053 {\n  padding-top: 0px;\n  padding-bottom: 0px;\n}\n<\/style>\n\t<\/section>\n\t\r\n\t<section class=\"section\" id=\"section_990949448\">\n\t\t<div class=\"bg section-bg fill bg-fill  bg-loaded\" >\n\n\t\t\t\n\t\t\t\n\t\t\t\n\n\t\t<\/div>\n\n\t\t<div class=\"section-content relative\">\n\t\t\t\r\n\r\n<div class=\"row\"  id=\"row-630720953\">\r\n\r\n\n\t<div id=\"col-1037383142\" class=\"col small-12 large-12\"  >\n\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\r\n\r\n\t<div id=\"gap-405194098\" class=\"gap-element clearfix\" style=\"display:block; height:auto;\">\n\t\t\n<style>\n#gap-405194098 {\n  padding-top: 35px;\n}\n<\/style>\n\t<\/div>\n\t\r\n\r\n<div class=\"row row-collapse row-full-width\"  id=\"row-256878795\">\r\n\r\n\n\t<div id=\"col-1771877943\" class=\"col medium-6 small-12 large-6\"  >\n\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\r\n\r\n\n  <div class=\"banner has-hover\" id=\"banner-1241246336\">\n          <div class=\"banner-inner fill\">\n        <div class=\"banner-bg fill\" >\n            <div class=\"bg fill bg-fill \"><\/div>\n                                    \n                    <\/div>\n        <div class=\"banner-layers container\">\n            <div class=\"fill banner-link\"><\/div>            \r\n\r\n   <div id=\"text-box-1139776228\" class=\"text-box banner-layer x50 md-x50 lg-x50 y50 md-y50 lg-y50 res-text\">\n                                <div class=\"text \">\n              \n              <div class=\"text-inner text-center\">\n                  \r\n\r\n<h2 class=\"uppercase\"><strong>get in touch<\/strong><\/h2>\r\n<div class=\"text-center\"><div class=\"is-divider divider clearfix\" style=\"max-width:70px;\"><\/div><\/div>\r\n\r\n\t<div id=\"gap-1275361015\" class=\"gap-element clearfix\" style=\"display:block; height:auto;\">\n\t\t\n<style>\n#gap-1275361015 {\n  padding-top: 10px;\n}\n<\/style>\n\t<\/div>\n\t\r\n\r\n<div role=\"form\" class=\"wpcf7\" id=\"wpcf7-f1158-o1\" lang=\"en-US\" dir=\"ltr\">\n<div class=\"screen-reader-response\"><p role=\"status\" aria-live=\"polite\" aria-atomic=\"true\"><\/p> <ul><\/ul><\/div>\n<form action=\"\/web\/sajco\/wp-json\/wp\/v2\/pages\/359#wpcf7-f1158-o1\" method=\"post\" class=\"wpcf7-form init\" novalidate=\"novalidate\" data-status=\"init\">\n<div style=\"display: none;\">\n<input type=\"hidden\" name=\"_wpcf7\" value=\"1158\" \/>\n<input type=\"hidden\" name=\"_wpcf7_version\" value=\"5.3\" \/>\n<input type=\"hidden\" name=\"_wpcf7_locale\" value=\"en_US\" \/>\n<input type=\"hidden\" name=\"_wpcf7_unit_tag\" value=\"wpcf7-f1158-o1\" \/>\n<input type=\"hidden\" name=\"_wpcf7_container_post\" value=\"0\" \/>\n<input type=\"hidden\" name=\"_wpcf7_posted_data_hash\" value=\"\" \/>\n<\/div>\n<div class=\"form-flat\">\n<span class=\"wpcf7-form-control-wrap your-name\"><input type=\"text\" name=\"your-name\" value=\"\" size=\"40\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Your Name (required)\" \/><\/span><\/p>\n<p><span class=\"wpcf7-form-control-wrap your-email\"><input type=\"email\" name=\"your-email\" value=\"\" size=\"40\" class=\"wpcf7-form-control wpcf7-text wpcf7-email wpcf7-validates-as-required wpcf7-validates-as-email\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Your Email (required)\" \/><\/span> <\/p>\n<p><span class=\"wpcf7-form-control-wrap your-phone\"><input type=\"text\" name=\"your-phone\" value=\"\" size=\"40\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Phone Number (required)\" \/><\/span> <\/p>\n<p><span class=\"wpcf7-form-control-wrap your-message\"><textarea name=\"your-message\" cols=\"40\" rows=\"10\" class=\"wpcf7-form-control wpcf7-textarea\" aria-invalid=\"false\" placeholder=\"Your Message (required)\"><\/textarea><\/span> <\/p>\n<p><input type=\"submit\" value=\"Submit\" class=\"wpcf7-form-control wpcf7-submit button\" \/>\n<\/p><\/div>\n<div class=\"wpcf7-response-output\" aria-hidden=\"true\"><\/div><\/form><\/div>\r\n\r\n\r\n              <\/div>\n           <\/div>\n                            \n<style>\n#text-box-1139776228 {\n  width: 77%;\n}\n#text-box-1139776228 .text {\n  font-size: 140%;\n}\n<\/style>\n    <\/div>\n \r\n\r\n        <\/div>\n      <\/div>\n\n            \n<style>\n#banner-1241246336 {\n  padding-top: 499px;\n  background-color: rgb(255,255,255);\n}\n<\/style>\n  <\/div>\n\n\r\n\r\n\t\t<\/div>\n\t\t\t<\/div>\n\n\t\r\n\n\t<div id=\"col-1062700827\" class=\"col medium-6 small-12 large-6\"  >\n\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\r\n\r\n<!-- &#091;map height=\"499px\" lat=\"25.2376897\" long=\"55.3018949\" zoom=\"11\" pan=\"0\" content_bg=\"rgba(255, 255, 255, 0.97)\" content_width=\"50\" content_width__sm=\"100\" content_width__md=\"40\" position_x__sm=\"100\" position_y__sm=\"100\"&#093;\r\n\r\n<h4>Showroom 7, AL GOZE BUILDING - 437 Sheikh Zayed Rd - Al Quoz 1 - Dubai - United Arab Emirates<\/h4>\r\n&#091;button text=\"Find on GOOLE\" color=\"secondary\" expand=\"true\" link=\"https:\/\/goo.gl\/maps\/PKGfhSmhV3JmKN3eA\" target=\"_blank\"&#093;\r\n\r\n\r\n&#091;\/map&#093; -->\r\n<iframe src=\"https:\/\/www.google.com\/maps\/embed?pb=!1m18!1m12!1m3!1d3610.8709097073256!2d55.242063374440676!3d25.17383633264832!2m3!1f0!2f0!3f0!3m2!1i1024!2i768!4f13.1!3m3!1m2!1s0x3e5f690ed2552541%3A0xd75961db461a0bce!2sSaif%20and%20Jasser%20Trading%20Co.%20LLC!5e0!3m2!1sen!2sin!4v1701075765673!5m2!1sen!2sin\" width=\"525\" height=\"499\" style=\"border:0;\" allowfullscreen=\"\" loading=\"lazy\" referrerpolicy=\"no-referrer-when-downgrade\"><\/iframe>\r\n\r\n\t\t<\/div>\n\t\t\t<\/div>\n\n\t\r\n\r\n<\/div>\r\n\r\n\t\t<\/div>\n\t\t\t<\/div>\n\n\t\r\n\r\n<\/div>\r\n\r\n\t\t<\/div>\n\n\t\t\n<style>\n#section_990949448 {\n  padding-top: 30px;\n  padding-bottom: 30px;\n  background-color: rgb(231, 231, 231);\n}\n<\/style>\n\t<\/section>\n\t\r\n\t<section class=\"section brands_logo_homepage\" id=\"section_1633767238\">\n\t\t<div class=\"bg section-bg fill bg-fill  bg-loaded\" >\n\n\t\t\t\n\t\t\t\n\t\t\t\n\n\t\t<\/div>\n\n\t\t<div class=\"section-content relative\">\n\t\t\t\r\n\r\n\t<div id=\"gap-1816924699\" class=\"gap-element clearfix\" style=\"display:block; height:auto;\">\n\t\t\n<style>\n#gap-1816924699 {\n  padding-top: 50px;\n}\n<\/style>\n\t<\/div>\n\t\r\n\r\n<div class=\"row row-small align-center\"  id=\"row-1524375344\">\r\n\r\n\n\t<div id=\"col-1915569603\" class=\"col medium-10 small-12 large-12\"  data-animate=\"fadeInDown\">\n\t\t<div class=\"col-inner text-center\"  >\n\t\t\t\n\t\t\t\r\n\r\n<h1><span style=\"font-size: 50px; color: #0054a4;\">Brands We Work With<\/span><\/h1>\r\n<div class=\"is-divider divider clearfix\" ><\/div>\r\n\r\n\r\n\t\t<\/div>\n\t\t\t<\/div>\n\n\t\r\n\r\n<\/div>\r\n<div class=\"row align-middle align-center row-solid\"  id=\"row-766097716\">\r\n\r\n\n\t<div id=\"col-1548134301\" class=\"col small-6 large-12\"  data-animate=\"fadeInDown\">\n\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\r\n\r\n\t\t\t\t<style>\t\t\t\n\t\t\t#wpls-logo-showcase-slider-1 .wpls-fix-box,\n\t\t\t#wpls-logo-showcase-slider-1 .wpls-fix-box img.wp-post-image{max-height:250px; }\n\t\t<\/style>\n\t\t<div class=\"wpls-logo-showcase-slider-wrp wpls-logo-clearfix \">\n\t\t\t<div class=\"wpls-logo-showcase logo_showcase wpls-logo-slider  wpls-design-1  sliderimage_hide_border wpls-dots-false\" id=\"wpls-logo-showcase-slider-1\" >\n\t\t\t\t\n<div class=\"wpls-logo-cnt\">\n\t<div class=\"wpls-fix-box\">\n\t\t\t\t\t<a href=\"https:\/\/charnaud.net\/\" target=\"_self\">\n\t\t\t\t<img decoding=\"async\" class=\"wp-post-image\"  src=\"https:\/\/sda.in.net\/web\/sajco\/wp-content\/uploads\/2020\/10\/Aci-Flam-Logo.jpg\" title=\"Aci-Flam-Logo\" alt=\"\" \/>\n\t\t\t<\/a>\n\t\t\t<\/div>\n\t<\/div>\n<div class=\"wpls-logo-cnt\">\n\t<div class=\"wpls-fix-box\">\n\t\t\t\t\t<a href=\"https:\/\/charnaud.net\/\" target=\"_self\">\n\t\t\t\t<img decoding=\"async\" class=\"wp-post-image\"  src=\"https:\/\/sda.in.net\/web\/sajco\/wp-content\/uploads\/2020\/10\/AJ-Charnaud-Logo.jpg\" title=\"AJ-Charnaud-Logo\" alt=\"\" \/>\n\t\t\t<\/a>\n\t\t\t<\/div>\n\t<\/div>\n<div class=\"wpls-logo-cnt\">\n\t<div class=\"wpls-fix-box\">\n\t\t\t\t\t<a href=\"https:\/\/charnaud.net\/\" target=\"_self\">\n\t\t\t\t<img decoding=\"async\" class=\"wp-post-image\"  src=\"https:\/\/sda.in.net\/web\/sajco\/wp-content\/uploads\/2020\/10\/Alu-Safe-Logo.jpg\" title=\"Alu-Safe-Logo\" alt=\"\" \/>\n\t\t\t<\/a>\n\t\t\t<\/div>\n\t<\/div>\n<div class=\"wpls-logo-cnt\">\n\t<div class=\"wpls-fix-box\">\n\t\t\t\t\t<a href=\"https:\/\/www.blsgroup.it\/\" target=\"_self\">\n\t\t\t\t<img decoding=\"async\" class=\"wp-post-image\"  src=\"https:\/\/sda.in.net\/web\/sajco\/wp-content\/uploads\/2020\/10\/BLS-Logo.jpg\" title=\"BLS-Logo\" alt=\"\" \/>\n\t\t\t<\/a>\n\t\t\t<\/div>\n\t<\/div>\n<div class=\"wpls-logo-cnt\">\n\t<div class=\"wpls-fix-box\">\n\t\t\t\t\t<a href=\"https:\/\/centurionsafety.eu\/\" target=\"_self\">\n\t\t\t\t<img decoding=\"async\" class=\"wp-post-image\"  src=\"https:\/\/sda.in.net\/web\/sajco\/wp-content\/uploads\/2020\/10\/Cenutrion-Helmets-Logo.jpg\" title=\"Cenutrion-Helmets-Logo\" alt=\"\" \/>\n\t\t\t<\/a>\n\t\t\t<\/div>\n\t<\/div>\n<div class=\"wpls-logo-cnt\">\n\t<div class=\"wpls-fix-box\">\n\t\t\t\t\t<a href=\"https:\/\/www.felo.com\/en\/\" target=\"_self\">\n\t\t\t\t<img decoding=\"async\" class=\"wp-post-image\"  src=\"https:\/\/sda.in.net\/web\/sajco\/wp-content\/uploads\/2020\/10\/Felo-Logo.jpg\" title=\"Felo-Logo\" alt=\"\" \/>\n\t\t\t<\/a>\n\t\t\t<\/div>\n\t<\/div>\n<div class=\"wpls-logo-cnt\">\n\t<div class=\"wpls-fix-box\">\n\t\t\t\t\t<a href=\"http:\/\/www.giasco.com\/eng\/\" target=\"_self\">\n\t\t\t\t<img decoding=\"async\" class=\"wp-post-image\"  src=\"https:\/\/sda.in.net\/web\/sajco\/wp-content\/uploads\/2020\/10\/galsco.jpg\" title=\"galsco\" alt=\"\" \/>\n\t\t\t<\/a>\n\t\t\t<\/div>\n\t<\/div>\n<div class=\"wpls-logo-cnt\">\n\t<div class=\"wpls-fix-box\">\n\t\t\t\t\t<a href=\"https:\/\/www.giordanigiancarlo.com\/en\/\" target=\"_self\">\n\t\t\t\t<img decoding=\"async\" class=\"wp-post-image\"  src=\"https:\/\/sda.in.net\/web\/sajco\/wp-content\/uploads\/2020\/10\/Giordani-Logo.jpg\" title=\"Giordani-Logo\" alt=\"\" \/>\n\t\t\t<\/a>\n\t\t\t<\/div>\n\t<\/div>\n<div class=\"wpls-logo-cnt\">\n\t<div class=\"wpls-fix-box\">\n\t\t\t\t\t<a href=\"https:\/\/globusgroup.com\/\" target=\"_self\">\n\t\t\t\t<img decoding=\"async\" class=\"wp-post-image\"  src=\"https:\/\/sda.in.net\/web\/sajco\/wp-content\/uploads\/2020\/10\/Globus-Logo.jpg\" title=\"Globus-Logo\" alt=\"\" \/>\n\t\t\t<\/a>\n\t\t\t<\/div>\n\t<\/div>\n<div class=\"wpls-logo-cnt\">\n\t<div class=\"wpls-fix-box\">\n\t\t\t\t\t<a href=\"https:\/\/www.honeywell.com\/en-us\" target=\"_self\">\n\t\t\t\t<img decoding=\"async\" class=\"wp-post-image\"  src=\"https:\/\/sda.in.net\/web\/sajco\/wp-content\/uploads\/2020\/08\/brand29.png\" title=\"brand29\" alt=\"\" \/>\n\t\t\t<\/a>\n\t\t\t<\/div>\n\t<\/div>\n<div class=\"wpls-logo-cnt\">\n\t<div class=\"wpls-fix-box\">\n\t\t\t\t\t<a href=\"https:\/\/www.lucartprofessional.com\/en\/united-kingdom\/lucartsas-export\/home\/\" target=\"_self\">\n\t\t\t\t<img decoding=\"async\" class=\"wp-post-image\"  src=\"https:\/\/sda.in.net\/web\/sajco\/wp-content\/uploads\/2020\/10\/Lucart-Logo.jpg\" title=\"Lucart-Logo\" alt=\"\" \/>\n\t\t\t<\/a>\n\t\t\t<\/div>\n\t<\/div>\n<div class=\"wpls-logo-cnt\">\n\t<div class=\"wpls-fix-box\">\n\t\t\t\t\t<a href=\"https:\/\/www.makitatools.com\/\" target=\"_self\">\n\t\t\t\t<img decoding=\"async\" class=\"wp-post-image\"  src=\"https:\/\/sda.in.net\/web\/sajco\/wp-content\/uploads\/2020\/10\/Makita-Logo.jpg\" title=\"Makita-Logo\" alt=\"\" \/>\n\t\t\t<\/a>\n\t\t\t<\/div>\n\t<\/div>\n<div class=\"wpls-logo-cnt\">\n\t<div class=\"wpls-fix-box\">\n\t\t\t\t\t<a href=\"https:\/\/www.pantaiwan.com.tw\/\" target=\"_self\">\n\t\t\t\t<img decoding=\"async\" class=\"wp-post-image\"  src=\"https:\/\/sda.in.net\/web\/sajco\/wp-content\/uploads\/2020\/10\/Pan-Taiwan-Logo.jpg\" title=\"Pan-Taiwan-Logo\" alt=\"\" \/>\n\t\t\t<\/a>\n\t\t\t<\/div>\n\t<\/div>\n<div class=\"wpls-logo-cnt\">\n\t<div class=\"wpls-fix-box\">\n\t\t\t\t\t<a href=\"http:\/\/www.makritenorthamerica.com\/\" target=\"_self\">\n\t\t\t\t<img decoding=\"async\" class=\"wp-post-image\"  src=\"https:\/\/sda.in.net\/web\/sajco\/wp-content\/uploads\/2020\/10\/PMAX-Logo-Side.jpg\" title=\"PMAX-Logo-Side\" alt=\"\" \/>\n\t\t\t<\/a>\n\t\t\t<\/div>\n\t<\/div>\n<div class=\"wpls-logo-cnt\">\n\t<div class=\"wpls-fix-box\">\n\t\t\t\t\t<a href=\"https:\/\/www.respair.co.uk\/\" target=\"_self\">\n\t\t\t\t<img decoding=\"async\" class=\"wp-post-image\"  src=\"https:\/\/sda.in.net\/web\/sajco\/wp-content\/uploads\/2020\/10\/Respair-Logo.jpg\" title=\"Respair-Logo\" alt=\"\" \/>\n\t\t\t<\/a>\n\t\t\t<\/div>\n\t<\/div>\t\t\t<\/div>\n\t\t\t<div class=\"wpls-logo-showacse-slider-conf\" data-conf=\"{&quot;slides_column&quot;:&quot;4&quot;,&quot;slides_scroll&quot;:&quot;1&quot;,&quot;dots&quot;:&quot;false&quot;,&quot;arrows&quot;:&quot;true&quot;,&quot;autoplay&quot;:&quot;true&quot;,&quot;autoplay_interval&quot;:&quot;2000&quot;,&quot;loop&quot;:&quot;true&quot;,&quot;rtl&quot;:&quot;false&quot;,&quot;speed&quot;:&quot;1000&quot;,&quot;center_mode&quot;:&quot;false&quot;,&quot;lazyload&quot;:&quot;&quot;}\"><\/div>\n\t\t<\/div>\n\t\t\t\n\t\t\r\n\r\n\t\t<\/div>\n\t\t\t<\/div>\n\n\t\r\n\r\n<\/div>\r\n\t<div id=\"gap-1345766657\" class=\"gap-element clearfix\" style=\"display:block; height:auto;\">\n\t\t\n<style>\n#gap-1345766657 {\n  padding-top: 50px;\n}\n<\/style>\n\t<\/div>\n\t\r\n\r\n\r\n\t\t<\/div>\n\n\t\t\n<style>\n#section_1633767238 {\n  padding-top: 0px;\n  padding-bottom: 0px;\n}\n<\/style>\n\t<\/section>\n\t\r\n\r\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"page-blank.php","meta":{"footnotes":""},"class_list":["post-359","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/sda.in.net\/web\/sajco\/wp-json\/wp\/v2\/pages\/359","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sda.in.net\/web\/sajco\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/sda.in.net\/web\/sajco\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/sda.in.net\/web\/sajco\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/sda.in.net\/web\/sajco\/wp-json\/wp\/v2\/comments?post=359"}],"version-history":[{"count":15,"href":"https:\/\/sda.in.net\/web\/sajco\/wp-json\/wp\/v2\/pages\/359\/revisions"}],"predecessor-version":[{"id":1930,"href":"https:\/\/sda.in.net\/web\/sajco\/wp-json\/wp\/v2\/pages\/359\/revisions\/1930"}],"wp:attachment":[{"href":"https:\/\/sda.in.net\/web\/sajco\/wp-json\/wp\/v2\/media?parent=359"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}